{"id":30343,"date":"2023-10-18T08:53:23","date_gmt":"2023-10-18T06:53:23","guid":{"rendered":"https:\/\/muenzinger.eu\/sostenibilita-completa\/"},"modified":"2024-04-18T14:32:22","modified_gmt":"2024-04-18T12:32:22","slug":"sostenibilita-completa","status":"publish","type":"page","link":"https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/","title":{"rendered":"Sostenibilit\u00e0 completa"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_e767e4a2 height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container col-overview-menu has_bg_color has-link\"><div class=\"vc_column-inner us_custom_bbe431a8\"><div class=\"vc_column-overlay\" style=\"background:rgba(0,0,0,0.5)\"><\/div><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_2103bcca underline has_text_color\"><div class=\"wpb_wrapper\"><h6><strong>Chi siamo<\/strong><\/h6>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><a title=\"\u00dcber uns\" href=\"https:\/\/muenzinger.eu\/ueber-uns\/\" class=\"vc_column-link smooth-scroll\"><\/a><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container col-overview-menu has_bg_color has-link\"><div class=\"vc_column-inner us_custom_c7e0464b\"><div class=\"vc_column-overlay\" style=\"background:rgba(0,0,0,0.5)\"><\/div><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_2103bcca underline has_text_color\"><div class=\"wpb_wrapper\"><h6><strong>Luoghi<\/strong><\/h6>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><a title=\"Standorte\" href=\"https:\/\/muenzinger.eu\/standorte\/\" class=\"vc_column-link smooth-scroll\"><\/a><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container col-overview-menu has_bg_color has-link\"><div class=\"vc_column-inner us_custom_c9d9114a\"><div class=\"vc_column-overlay\" style=\"background:rgba(0,0,0,0.5)\"><\/div><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_2103bcca underline has_text_color\"><div class=\"wpb_wrapper\"><h6><strong>La nostra promessa<\/strong><\/h6>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><a title=\"Unser Versprechen\" href=\"https:\/\/muenzinger.eu\/unser-versprechen\/\" class=\"vc_column-link smooth-scroll\"><\/a><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container col-overview-menu has_bg_color has-link\"><div class=\"vc_column-inner us_custom_f0a9d620\"><div class=\"vc_column-overlay\" style=\"background:rgba(0,0,0,0.5)\"><\/div><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_2103bcca underline has_text_color\"><div class=\"wpb_wrapper\"><h6><strong>Sostenibilit\u00e0<\/strong><\/h6>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><a title=\"Nachhaltigkeit\" href=\"https:\/\/muenzinger.eu\/nachhaltigkeit-komplett\/\" class=\"vc_column-link smooth-scroll\"><\/a><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container col-overview-menu has_bg_color has-link\"><div class=\"vc_column-inner us_custom_8be06b1b\"><div class=\"vc_column-overlay\" style=\"background:rgba(0,0,0,0.5)\"><\/div><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_2103bcca underline has_text_color\"><div class=\"wpb_wrapper\"><h6><strong>Carriera<\/strong><\/h6>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><a title=\"Karriere\" href=\"https:\/\/muenzinger.eu\/karriere\/\" class=\"vc_column-link smooth-scroll\"><\/a><\/div><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_502d7613 height_auto color_alternate with_img\"><div class=\"l-section-img\" style=\"background-image: url(https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/12\/Nachhaltigkeit-scaled.jpg);background-position: center right;background-repeat: no-repeat;\" data-img-width=\"3800\" data-img-height=\"1931\"><\/div><div class=\"l-section-overlay\" style=\"background:linear-gradient(255deg,rgba(0,0,0,0.45),rgba(0,0,0,0.65))\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-9 vc_col-lg-6 vc_col-md-8 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 vc_hidden-lg vc_hidden-md vc_hidden-sm wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator hide_on_mobiles size_medium\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_de366d1c us_animate_this\"><div class=\"wpb_wrapper\"><div class=\"w-separator hide_on_default hide_on_laptops size_small\"><\/div><div class=\"wpb_text_column us_custom_521988b2 has_text_color us_animate_this\"><div class=\"wpb_wrapper\"><h5>Sostenibilit\u00e0<\/h5>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column us_custom_ab3c1c91 has_text_color us_animate_this\"><div class=\"wpb_wrapper\"><p><span style=\"color: #e11900;\">Iso\u00adlare in modo sos\u00adteni\u00adbile e rispar\u00admiare ener\u00adgia a lungo ter\u00admine.<\/span><\/p>\n<\/div><\/div><div class=\"w-separator hide_on_default hide_on_laptops hide_on_tablets size_small\"><\/div><div class=\"g-cols wpb_row us_custom_0d66a9f7 us_animate_this via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_432d3f53\"><div class=\"wpb_wrapper\"><p>In qua\u00adlit\u00e0 di azi\u00adenda che tratta il tema dei sis\u00adtemi di iso\u00adla\u00admento da zero con la sos\u00adteni\u00adbi\u00adlit\u00e0 e il rispar\u00admio ener\u00adge\u00adtico, noi della M\u00fcnz\u00adin\u00adger + Frie\u00adser Hol\u00adding GmbH per\u00adse\u00adguiamo una cul\u00adtura azi\u00adend\u00adale ris\u00adpet\u00adtosa del\u00adl\u2019am\u00adbi\u00adente e delle risorse. Abbiamo rico\u00adno\u00adsci\u00aduto che nel mondo di oggi \u00e8 importante anche agire in modo eco\u00adlo\u00adgi\u00adca\u00admente responsa\u00adbile e assu\u00admersi la responsa\u00adbi\u00adlit\u00e0 sociale.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator hide_on_mobiles size_medium\"><\/div><div class=\"w-separator hide_on_mobiles size_medium\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 vc_hidden-lg vc_hidden-md vc_hidden-sm wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_medium\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_a518f36e us_animate_this height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_medium\"><\/div><div class=\"w-separator us_custom_8f2ba1f4 us_animate_this size_custom with_line width_50 thick_4 style_solid color_secondary align_center\" style=\"height:4px\"><div class=\"w-separator-h\"><\/div><\/div><div class=\"w-separator size_medium\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-12 vc_col-lg-6 vc_col-md-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 vc_col-lg-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image hide_on_tablets hide_on_mobiles has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"2121\" height=\"1414\" src=\"https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/06\/iStock-1412012308.jpg\" class=\"attachment-full size-full\" alt srcset=\"https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/06\/iStock-1412012308.jpg 2121w, https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/06\/iStock-1412012308-300x200.jpg 300w, https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/06\/iStock-1412012308-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 2121px) 100vw, 2121px\"><\/div><\/div><div class=\"w-image hide_on_default hide_on_laptops has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:56.25%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"2121\" height=\"1414\" src=\"https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/06\/iStock-1412012308.jpg\" class=\"attachment-full size-full\" alt srcset=\"https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/06\/iStock-1412012308.jpg 2121w, https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/06\/iStock-1412012308-300x200.jpg 300w, https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/06\/iStock-1412012308-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 2121px) 100vw, 2121px\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-12 vc_col-lg-6 vc_col-md-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator hide_on_default hide_on_laptops size_medium\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><span style=\"color: var(--color-content-primary);\">Sostenibilit\u00e0<\/span><\/h2>\n<\/div><\/div><div class=\"wpb_text_column us_custom_6876e3bd has_text_color\"><div class=\"wpb_wrapper\"><h5>Siamo orgogliosi di essere un\u2019azienda che persegue la sostenibilit\u00e0 come strategia aziendale centrale e che contribuisce alla riduzione delle emissioni di CO\u00b2 a livello nazionale con i nostri prodotti.<\/h5>\n<\/div><\/div><div class=\"wpb_text_column us_custom_432d3f53\"><div class=\"wpb_wrapper\"><p>Un ele\u00admento cen\u00adtrale della nos\u00adtra stra\u00adte\u00adgia di sos\u00adteni\u00adbi\u00adlit\u00e0 \u00e8 la pro\u00admo\u00adzione di tec\u00adno\u00adlo\u00adgie effi\u00adci\u00adenti dal punto di vista ener\u00adge\u00adtico e di ener\u00adgie rin\u00adno\u00adva\u00adbili, al fine di ridurre al minimo il con\u00adsumo di ener\u00adgia e le emis\u00adsioni di CO2. Uti\u00adliz\u00adzando l\u2019il\u00adlu\u00admi\u00adna\u00adzione a LED, sis\u00adtemi intel\u00adli\u00adgenti di ges\u00adtione degli edi\u00adfici e una ges\u00adtione effi\u00adci\u00adente dei rifi\u00aduti, con\u00adtri\u00adbuiamo atti\u00adva\u00admente alla pro\u00adte\u00adzione del clima e abbiamo gi\u00e0 con\u00adtri\u00adbuito a miglio\u00adrare la nos\u00adtra impronta di car\u00adbo\u00adnio con diversi pro\u00adgetti. Abbiamo gi\u00e0 inves\u00adtito nelle ener\u00adgie rin\u00adno\u00adva\u00adbili, come le auto elett\u00adri\u00adche, le sta\u00adzioni di rica\u00adrica elett\u00adro\u00adnica e gli impianti solari. Siamo inoltre impeg\u00adnati in una catena di approv\u00advi\u00adgio\u00adna\u00admento sos\u00adteni\u00adbile e lavo\u00adr\u00adiamo per garan\u00adtire che anche i nos\u00adtri part\u00adner com\u00admer\u00adciali adottino pra\u00adti\u00adche ris\u00adpet\u00adtose del\u00adl\u2019am\u00adbi\u00adente. Con le nostre 9 sedi in Ger\u00adma\u00adnia e 3 sedi in Aus\u00adtria, siamo anche pi\u00f9 vicini ai nos\u00adtri cli\u00adenti e quindi abbiamo per\u00adcorsi di con\u00adsegna pi\u00f9 brevi.<\/p>\n<p>Un altro aspetto importante del nos\u00adtro impegno per la sos\u00adteni\u00adbi\u00adlit\u00e0 \u00e8 la responsa\u00adbi\u00adlit\u00e0 sociale. Attri\u00adbuiamo grande import\u00adanza a con\u00addi\u00adzioni di lavoro eque e alla pro\u00admo\u00adzione della diver\u00adsit\u00e0 e delle pari oppor\u00adtu\u00adnit\u00e0. Siamo inoltre impeg\u00adnati in pro\u00adgetti sociali e orga\u00adniz\u00adza\u00adzioni di bene\u00adficenza nella nos\u00adtra regione.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_large\"><\/div><div class=\"w-separator us_custom_8f2ba1f4 us_animate_this size_custom with_line width_50 thick_4 style_solid color_secondary align_center\" style=\"height:4px\"><div class=\"w-separator-h\"><\/div><\/div><div class=\"w-separator size_large\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\" id=\"sostenibilit\u00e0\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-12 vc_col-lg-6 vc_col-md-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_de366d1c us_animate_this\"><div class=\"wpb_wrapper\"><div class=\"w-image hide_on_default hide_on_laptops has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:56.25%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1641\" src=\"https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/10\/nachhaltigkeit-2.jpg\" class=\"attachment-full size-full\" alt srcset=\"https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/10\/nachhaltigkeit-2.jpg 2000w, https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/10\/nachhaltigkeit-2-300x246.jpg 300w, https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/10\/nachhaltigkeit-2-1024x840.jpg 1024w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\"><\/div><\/div><div class=\"w-separator hide_on_default hide_on_laptops size_medium\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><span style=\"color: var(--color-content-primary);\">Il nostro impegno<\/span><\/h2>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_text_column us_custom_6876e3bd has_text_color\"><div class=\"wpb_wrapper\"><h5>Siamo in costante evoluzione in termini di sostenibilit\u00e0. Ecco alcuni dei modi in cui abbiamo gi\u00e0 contribuito a ridurre le emissioni di CO\u00b2.<\/h5>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-2 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_4cfc8534 iconpos_top style_circle color_custom align_center no_title no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:1.0rem;background:var(--color-content-bg-alt);color:var(--color-content-primary);\"><i class=\"fas fa-check\"><\/i><\/div><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h5>Energia geotermica<\/h5>\n<p>Uti\u00adliz\u00adziamo sis\u00adtemi di ris\u00adcal\u00adda\u00admento alter\u00adna\u00adtivi come l\u2019ener\u00adgia geo\u00adter\u00admica.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-2 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_4cfc8534 iconpos_top style_circle color_custom align_center no_title no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:1.0rem;background:var(--color-content-bg-alt);color:var(--color-content-primary);\"><i class=\"fas fa-check\"><\/i><\/div><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h5>Carrello elevatore elettrico<\/h5>\n<p>In tutte le sedi ven\u00adgono uti\u00adliz\u00adzati car\u00adrelli ele\u00adva\u00adtori elett\u00adrici.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-2 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_4cfc8534 iconpos_top style_circle color_custom align_center no_title no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:1.0rem;background:var(--color-content-bg-alt);color:var(--color-content-primary);\"><i class=\"fas fa-check\"><\/i><\/div><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h5>Auto elettriche<\/h5>\n<p>Abbiamo gi\u00e0 diverse auto elett\u00adri\u00adche nella nos\u00adtra flotta.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-2 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_4cfc8534 iconpos_top style_circle color_custom align_center no_title no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:1.0rem;background:var(--color-content-bg-alt);color:var(--color-content-primary);\"><i class=\"fas fa-check\"><\/i><\/div><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h5>Stazioni di rifornimento elettronico in alcune localit\u00e0<\/h5>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-2 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_4cfc8534 iconpos_top style_circle color_custom align_center no_title no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:1.0rem;background:var(--color-content-bg-alt);color:var(--color-content-primary);\"><i class=\"fas fa-check\"><\/i><\/div><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h5>Sistemi solari su diversi edifici<\/h5>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-2 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_4cfc8534 iconpos_top style_circle color_custom align_center no_title no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:1.0rem;background:var(--color-content-bg-alt);color:var(--color-content-primary);\"><i class=\"fas fa-check\"><\/i><\/div><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h5>Lampadine e lampade a LED<\/h5>\n<p>I nos\u00adtri uffici e magazzini sono dotati di LED.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-2 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_4cfc8534 iconpos_top style_circle color_custom align_center no_title no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:1.0rem;background:var(--color-content-bg-alt);color:var(--color-content-primary);\"><i class=\"fas fa-check\"><\/i><\/div><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h5>Doniamo 10\u20ac a www.meinwald.de<\/h5>\n<p>per ogni cli\u00adente che passa alla fat\u00adtu\u00adra\u00adzione elett\u00adro\u00adnica.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><\/div><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-2 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_4cfc8534 iconpos_top style_circle color_custom align_center no_title no_text\"><div class=\"w-iconbox-icon\" style=\"font-size:1.0rem;background:var(--color-content-bg-alt);color:var(--color-content-primary);\"><i class=\"fas fa-check\"><\/i><\/div><div class=\"w-iconbox-meta\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h5>L\u2019impegno sociale \u00e8 per noi una cosa ovvia<\/h5>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Fac\u00adciamo rego\u00adlar\u00admente dona\u00adzioni al \u201cF\u00f6r\u00adder\u00adver\u00adein f\u00fcr krebs\u00adkranke Kin\u00adder T\u00fcbin\u00adgen e.V.\u201d e al \u201cF\u00f6r\u00adder\u00adver\u00adein Son\u00adnen\u00adstrah\u00adlen e.V.\u201d.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-12 vc_col-lg-6 vc_col-md-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 vc_col-lg-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image hide_on_tablets hide_on_mobiles has_ratio align_none\"><div class=\"w-image-h\"><div style=\"padding-bottom:100%\"><\/div><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1641\" src=\"https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/10\/nachhaltigkeit-2.jpg\" class=\"attachment-full size-full\" alt srcset=\"https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/10\/nachhaltigkeit-2.jpg 2000w, https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/10\/nachhaltigkeit-2-300x246.jpg 300w, https:\/\/muenzinger.eu\/wp-content\/uploads\/2023\/10\/nachhaltigkeit-2-1024x840.jpg 1024w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-2 vc_hidden-sm vc_hidden-xs wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_medium\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Chi siamo Luoghi La nos\u00adtra pro\u00admessa Sos\u00adteni\u00adbi\u00adlit\u00e0 Car\u00adri\u00adera Sos\u00adteni\u00adbi\u00adlit\u00e0 Iso\u00adlare in modo sos\u00adteni\u00adbile e rispar\u00admiare ener\u00adgia a lungo ter\u00admine. In qua\u00adlit\u00e0 di azi\u00adenda che tratta il tema dei sis\u00adtemi di iso\u00adla\u00admento da zero con la sos\u00adteni\u00adbi\u00adlit\u00e0 e il rispar\u00admio ener\u00adge\u00adtico, noi della M\u00fcnz\u00adin\u00adger + Frie\u00adser Hol\u00adding GmbH per\u00adse\u00adguiamo una cul\u00adtura azi\u00adend\u00adale ris\u00adpet\u00adtosa del\u00adl\u2019am\u00adbi\u00adente e delle\u2026","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-30343","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sostenibilit\u00e0 completa - M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sostenibilit\u00e0 completa - M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T12:32:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/sostenibilita-completa\\\/\",\"url\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/sostenibilita-completa\\\/\",\"name\":\"Sostenibilit\u00e0 completa - M\u00fcnzinger + Frieser Holding GmbH \\\/ Adhesive D\u00e4mmsysteme GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/#website\"},\"datePublished\":\"2023-10-18T06:53:23+00:00\",\"dateModified\":\"2024-04-18T12:32:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/sostenibilita-completa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/muenzinger.eu\\\/it\\\/sostenibilita-completa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/sostenibilita-completa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina iniziale\",\"item\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sostenibilit\u00e0 completa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/\",\"name\":\"M\u00fcnzinger + Frieser Holding GmbH \\\/ Adhesive D\u00e4mmsysteme GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/#organization\",\"name\":\"M\u00fcnzinger + Frieser Holding GmbH \\\/ Adhesive D\u00e4mmsysteme GmbH\",\"url\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/muenzinger.eu\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Muenzinger-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/muenzinger.eu\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Muenzinger-logo-01.png\",\"width\":580,\"height\":107,\"caption\":\"M\u00fcnzinger + Frieser Holding GmbH \\\/ Adhesive D\u00e4mmsysteme GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/muenzinger.eu\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mnzinger-frieser-holding-gmbh\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sostenibilit\u00e0 completa - M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/","og_locale":"it_IT","og_type":"article","og_title":"Sostenibilit\u00e0 completa - M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH","og_url":"https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/","og_site_name":"M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH","article_modified_time":"2024-04-18T12:32:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/","url":"https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/","name":"Sostenibilit\u00e0 completa - M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH","isPartOf":{"@id":"https:\/\/muenzinger.eu\/it\/#website"},"datePublished":"2023-10-18T06:53:23+00:00","dateModified":"2024-04-18T12:32:22+00:00","breadcrumb":{"@id":"https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/muenzinger.eu\/it\/sostenibilita-completa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina iniziale","item":"https:\/\/muenzinger.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Sostenibilit\u00e0 completa"}]},{"@type":"WebSite","@id":"https:\/\/muenzinger.eu\/it\/#website","url":"https:\/\/muenzinger.eu\/it\/","name":"M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH","description":"","publisher":{"@id":"https:\/\/muenzinger.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/muenzinger.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/muenzinger.eu\/it\/#organization","name":"M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH","url":"https:\/\/muenzinger.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/muenzinger.eu\/it\/#\/schema\/logo\/image\/","url":"https:\/\/muenzinger.eu\/wp-content\/uploads\/2022\/12\/Muenzinger-logo-01.png","contentUrl":"https:\/\/muenzinger.eu\/wp-content\/uploads\/2022\/12\/Muenzinger-logo-01.png","width":580,"height":107,"caption":"M\u00fcnzinger + Frieser Holding GmbH \/ Adhesive D\u00e4mmsysteme GmbH"},"image":{"@id":"https:\/\/muenzinger.eu\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/mnzinger-frieser-holding-gmbh\/"]}]}},"_links":{"self":[{"href":"https:\/\/muenzinger.eu\/it\/wp-json\/wp\/v2\/pages\/30343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muenzinger.eu\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/muenzinger.eu\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/muenzinger.eu\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/muenzinger.eu\/it\/wp-json\/wp\/v2\/comments?post=30343"}],"version-history":[{"count":0,"href":"https:\/\/muenzinger.eu\/it\/wp-json\/wp\/v2\/pages\/30343\/revisions"}],"wp:attachment":[{"href":"https:\/\/muenzinger.eu\/it\/wp-json\/wp\/v2\/media?parent=30343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}